{"id":86,"date":"2020-02-03T08:02:52","date_gmt":"2020-02-03T07:02:52","guid":{"rendered":"https:\/\/bridge324.qodeinteractive.com\/?page_id=86"},"modified":"2020-11-25T09:16:22","modified_gmt":"2020-11-25T08:16:22","slug":"contact","status":"publish","type":"page","link":"https:\/\/pmgscotsman.com\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"86\" class=\"elementor elementor-86\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68c5984 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"68c5984\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4a4e75\" data-id=\"d4a4e75\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-afecb62 elementor-widget elementor-widget-image\" data-id=\"afecb62\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"316\" src=\"https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1.jpg\" class=\"attachment-full size-full\" alt=\"h\" srcset=\"https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1.jpg 1920w, https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1-300x49.jpg 300w, https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1-1024x169.jpg 1024w, https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1-768x126.jpg 768w, https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1-1536x253.jpg 1536w, https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1-700x115.jpg 700w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ce1574 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"7ce1574\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9343866\" data-id=\"9343866\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc04f84 elementor-widget elementor-widget-heading\" data-id=\"cc04f84\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Contact<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d95065e elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"d95065e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-02a6ba5\" data-id=\"02a6ba5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-836b9f3 elementor-widget elementor-widget-heading\" data-id=\"836b9f3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\">Perfectoin in a glass<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e20bac elementor-widget elementor-widget-spacer\" data-id=\"8e20bac\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-296a7b3 elementor-widget elementor-widget-heading\" data-id=\"296a7b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Get in touch <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b955b7e elementor-widget elementor-widget-spacer\" data-id=\"b955b7e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-305eb06 elementor-widget elementor-widget-spacer\" data-id=\"305eb06\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e58750 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"0e58750\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f2af35\" data-id=\"3f2af35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd7c72f elementor-widget elementor-widget-image\" data-id=\"dd7c72f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"395\" height=\"400\" src=\"https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/09\/peter.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/09\/peter.jpg 395w, https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/09\/peter-296x300.jpg 296w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e19b11a\" data-id=\"e19b11a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c719add elementor-widget elementor-widget-image\" data-id=\"c719add\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"950\" height=\"652\" src=\"https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/contact-image-3.jpg\" class=\"attachment-full size-full\" alt=\"h\" srcset=\"https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/contact-image-3.jpg 950w, https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/contact-image-3-300x206.jpg 300w, https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/contact-image-3-768x527.jpg 768w, https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/contact-image-3-700x480.jpg 700w\" sizes=\"auto, (max-width: 950px) 100vw, 950px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8efe710 elementor-section-full_width qode_elementor_container_inner elementor-section-height-default elementor-section-height-default parallax_section_no\" data-id=\"8efe710\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3f08a24\" data-id=\"3f08a24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-788e40e elementor-widget elementor-widget-heading\" data-id=\"788e40e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">contact<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-69eef72 elementor-section-full_width elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"69eef72\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-59cdc57\" data-id=\"59cdc57\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d4b50c elementor-widget elementor-widget-spacer\" data-id=\"0d4b50c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf2d624 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bf2d624\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-envelope\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">info@pmgscotsman.com<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+41 24 441 60 25<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-chess-rook\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Chemin du Passon 2, 1350 Orbe<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3318090\" data-id=\"3318090\" data-element_type=\"column\" id=\"message\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b062a2f elementor-widget elementor-widget-bridge_cf_7\" data-id=\"b062a2f\" data-element_type=\"widget\" data-widget_type=\"bridge_cf_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"qode-contact-form-7 qode-contact-form-7-0\">\n    <div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f28836-o1\" lang=\"fr-FR\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/86#wpcf7-f28836-o1\" method=\"post\" class=\"wpcf7-form init cf7_custom_style_1\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"28836\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.4.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"fr_FR\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f28836-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label> Votre Nom et Pr\u00e9nom*<br \/>\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Num\u00e9ro de t\u00e9l\u00e9phone*<br \/>\n    <span class=\"wpcf7-form-control-wrap tel-369\"><input type=\"tel\" name=\"tel-369\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-required wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Votre adresse de messagerie*<br \/>\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Sujet<br \/>\n    <span class=\"wpcf7-form-control-wrap your-subject\"><input type=\"text\" name=\"your-subject\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" \/><\/span> <\/label><\/p>\n<p><label> Votre message<br \/>\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\"><\/textarea><\/span> <\/label><\/p>\n<span class=\"wpcf7-form-control-wrap recaptcha\" data-name=\"recaptcha\"><span data-sitekey=\"6Lfbtd8ZAAAAAHrCDWpAETRKLHNBnxypx8PWHwfn\" class=\"wpcf7-form-control g-recaptcha wpcf7-recaptcha\"><\/span>\r\n<noscript>\r\n\t<div class=\"grecaptcha-noscript\">\r\n\t\t<iframe loading=\"lazy\" src=\"https:\/\/www.recaptcha.net\/recaptcha\/api\/fallback?k=6Lfbtd8ZAAAAAHrCDWpAETRKLHNBnxypx8PWHwfn\" frameborder=\"0\" scrolling=\"no\" width=\"310\" height=\"430\">\r\n\t\t<\/iframe>\r\n\t\t<textarea name=\"g-recaptcha-response\" rows=\"3\" cols=\"40\" placeholder=\"reCaptcha Response Here\">\r\n\t\t<\/textarea>\r\n\t<\/div>\r\n<\/noscript>\r\n<\/span>\n<p><input type=\"submit\" value=\"Envoyer\" class=\"wpcf7-form-control wpcf7-submit\" \/><\/p>\n<p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"45\"\/><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n\/* ]]> *\/\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><\/form><\/div>    <\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e10a15 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"2e10a15\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0282573\" data-id=\"0282573\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e93803 elementor-widget elementor-widget-google_maps\" data-id=\"6e93803\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe frameborder=\"0\" scrolling=\"no\" marginheight=\"0\" marginwidth=\"0\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Chemin%20du%20Passon%202%20%201350%20Orbe&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Chemin du Passon 2  1350 Orbe\"\n\t\t\t\t\taria-label=\"Chemin du Passon 2  1350 Orbe\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<footer class=\"elementor-section elementor-top-section elementor-element elementor-element-bbcec6d elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"bbcec6d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6c62541\" data-id=\"6c62541\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-55c6cd0 elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"55c6cd0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5f99dec\" data-id=\"5f99dec\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c8a3e0 elementor-widget elementor-widget-image\" data-id=\"0c8a3e0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"84\" src=\"https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/10\/web_537_logo_logo_small.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/10\/web_537_logo_logo_small.png 571w, https:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/10\/web_537_logo_logo_small-300x44.png 300w\" sizes=\"auto, (max-width: 571px) 100vw, 571px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-83152fa elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default parallax_section_no qode_elementor_container_no\" data-id=\"83152fa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-06fced1\" data-id=\"06fced1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c2191b elementor-widget elementor-widget-heading\" data-id=\"5c2191b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">COPYRIGHT \u00a9 ALL RIGHTS RESERVED.<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e171bf7\" data-id=\"e171bf7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5801adc elementor-widget elementor-widget-heading\" data-id=\"5801adc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Made with <span style=\"color: #ff0000;\">\u2764<\/span> by  M-Alexandre.com<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/footer>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Contact Perfectoin in a glass Get in touch contact info@pmgscotsman.com +41 24 441 60 25 Chemin du Passon 2, 1350 Orbe Votre Nom et Pr\u00e9nom* Num\u00e9ro de t\u00e9l\u00e9phone* Votre adresse de messagerie* Sujet Votre message COPYRIGHT \u00a9 ALL RIGHTS RESERVED. Made with \u2764 by M-Alexandre.com<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"full_width.php","meta":{"footnotes":""},"class_list":["post-86","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contact - PMG the Scotsman<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pmgscotsman.com\/en\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact - PMG the Scotsman\" \/>\n<meta property=\"og:description\" content=\"Contact Perfectoin in a glass Get in touch contact info@pmgscotsman.com +41 24 441 60 25 Chemin du Passon 2, 1350 Orbe Votre Nom et Pr\u00e9nom* Num\u00e9ro de t\u00e9l\u00e9phone* Votre adresse de messagerie* Sujet Votre message COPYRIGHT \u00a9 ALL RIGHTS RESERVED. Made with \u2764 by M-Alexandre.com\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pmgscotsman.com\/en\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"PMG the Scotsman\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-25T08:16:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/pmgscotsman.com\/#website\",\"url\":\"https:\/\/pmgscotsman.com\/\",\"name\":\"PMG the Scotsman\",\"description\":\"Des Whiskies d&#039;exception\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/pmgscotsman.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/pmgscotsman.com\/contact\/#primaryimage\",\"inLanguage\":\"en-GB\",\"url\":\"http:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1.jpg\",\"contentUrl\":\"http:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/pmgscotsman.com\/contact\/#webpage\",\"url\":\"https:\/\/pmgscotsman.com\/contact\/\",\"name\":\"Contact - PMG the Scotsman\",\"isPartOf\":{\"@id\":\"https:\/\/pmgscotsman.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/pmgscotsman.com\/contact\/#primaryimage\"},\"datePublished\":\"2020-02-03T07:02:52+00:00\",\"dateModified\":\"2020-11-25T08:16:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/pmgscotsman.com\/contact\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/pmgscotsman.com\/contact\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/pmgscotsman.com\/contact\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/pmgscotsman.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact - PMG the Scotsman","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pmgscotsman.com\/en\/contact\/","og_locale":"en_GB","og_type":"article","og_title":"Contact - PMG the Scotsman","og_description":"Contact Perfectoin in a glass Get in touch contact info@pmgscotsman.com +41 24 441 60 25 Chemin du Passon 2, 1350 Orbe Votre Nom et Pr\u00e9nom* Num\u00e9ro de t\u00e9l\u00e9phone* Votre adresse de messagerie* Sujet Votre message COPYRIGHT \u00a9 ALL RIGHTS RESERVED. Made with \u2764 by M-Alexandre.com","og_url":"https:\/\/pmgscotsman.com\/en\/contact\/","og_site_name":"PMG the Scotsman","article_modified_time":"2020-11-25T08:16:22+00:00","og_image":[{"url":"http:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1.jpg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/pmgscotsman.com\/#website","url":"https:\/\/pmgscotsman.com\/","name":"PMG the Scotsman","description":"Des Whiskies d&#039;exception","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pmgscotsman.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"ImageObject","@id":"https:\/\/pmgscotsman.com\/contact\/#primaryimage","inLanguage":"en-GB","url":"http:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1.jpg","contentUrl":"http:\/\/pmgscotsman.com\/wp-content\/uploads\/2020\/02\/recipe-image-1.jpg"},{"@type":"WebPage","@id":"https:\/\/pmgscotsman.com\/contact\/#webpage","url":"https:\/\/pmgscotsman.com\/contact\/","name":"Contact - PMG the Scotsman","isPartOf":{"@id":"https:\/\/pmgscotsman.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pmgscotsman.com\/contact\/#primaryimage"},"datePublished":"2020-02-03T07:02:52+00:00","dateModified":"2020-11-25T08:16:22+00:00","breadcrumb":{"@id":"https:\/\/pmgscotsman.com\/contact\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pmgscotsman.com\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pmgscotsman.com\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pmgscotsman.com\/"},{"@type":"ListItem","position":2,"name":"Contact"}]}]}},"_links":{"self":[{"href":"https:\/\/pmgscotsman.com\/en\/wp-json\/wp\/v2\/pages\/86","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pmgscotsman.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pmgscotsman.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pmgscotsman.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pmgscotsman.com\/en\/wp-json\/wp\/v2\/comments?post=86"}],"version-history":[{"count":24,"href":"https:\/\/pmgscotsman.com\/en\/wp-json\/wp\/v2\/pages\/86\/revisions"}],"predecessor-version":[{"id":29593,"href":"https:\/\/pmgscotsman.com\/en\/wp-json\/wp\/v2\/pages\/86\/revisions\/29593"}],"wp:attachment":[{"href":"https:\/\/pmgscotsman.com\/en\/wp-json\/wp\/v2\/media?parent=86"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}